{"id":568,"date":"2025-01-20T11:22:58","date_gmt":"2025-01-20T10:22:58","guid":{"rendered":"https:\/\/phmedien.rocks\/?p=568"},"modified":"2025-01-20T20:11:49","modified_gmt":"2025-01-20T19:11:49","slug":"daf-daz-zwischen-anspruechen-und-realitaet","status":"publish","type":"post","link":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/2025\/01\/20\/daf-daz-zwischen-anspruechen-und-realitaet\/","title":{"rendered":"DaF\/DaZ zwischen Anspr\u00fcchen und Realit\u00e4t"},"content":{"rendered":"\n<div class=\"wp-block-group alignwide is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading alignwide has-base-2-background-color has-background\" style=\"font-size:clamp(1.039rem, 1.039rem + ((1vw - 0.2rem) * 0.701), 1.6rem);\">Audio-Lernwerkstatt<\/h2>\n\n\n\n<p class=\"has-text-align-left has-base-background-color has-background has-heading-font-family has-small-font-size wp-block-paragraph\" style=\"border-style:none;border-width:0px;margin-top:0;margin-right:0;margin-bottom:0;margin-left:0;padding-top:0;padding-right:0;padding-bottom:0;padding-left:0;text-transform:none\">Herzlich willkommen zu einem fesselnden Gespr\u00e4ch rund um Deutsch als Fremdsprache (DaF) und Deutsch als Zweitsprache (DaZ) \u2013 speziell im Kontext von Deutschf\u00f6rderung in Schulen und der Erwachsenenbildung! Erfahrt mehr \u00fcber die Herausforderungen durch komplexe Rahmenbedingungen, mangelnde Ressourcen und die dringende Notwendigkeit eines Umdenkens im Unterricht, wobei es nicht nur um die Kluft zwischen Anspruch und Realit\u00e4t geht, sondern auch um die bedeutsame Integration von Sprachf\u00f6rderung in den gesamten Unterrichtsprozess. Lasst uns erkunden, warum eine individuelle F\u00f6rderung und umfassende Ressourcen auf allen Ebenen so entscheidend sind, um einen qualitativ hochwertigen Deutschunterricht zu gew\u00e4hrleisten.<\/p>\n\n\n\n<h2 class=\"wp-block-heading alignwide has-text-align-center has-contrast-2-color has-base-background-color has-text-color has-background has-link-color has-medium-font-size wp-elements-99227ddd712b4ee06ae362d2fb637693\">Podcast:<\/h2>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/phmedien.rocks\/wp-content\/uploads\/2024\/12\/Brenneis_Podcast-1.mp3\"><\/audio><\/figure>\n\n\n<p><iframe loading=\"lazy\" src=\"https:\/\/phwien.cloud.panopto.eu\/Panopto\/Pages\/Embed.aspx?id=169494a1-f1cd-4f99-9331-b24300d6e203&#038;autoplay=false&#038;offerviewer=true&#038;showtitle=true&#038;showbrand=true&#038;captions=false&#038;interactivity=all\" height=\"200\" width=\"100%\" style=\"border: 1px solid #464646;\" allowfullscreen allow=\"autoplay\" aria-label=\"In Panopto integrierter Videoplayer\" aria-description=\"DaF\/DaZ zwischen Anspr\u00fcchen und Realit\u00e4t\" ><\/iframe><\/p>\n\n\n\n<p class=\"has-base-background-color has-background has-small-font-size wp-block-paragraph\" style=\"padding-right:0;padding-left:0;text-transform:none\">Produziert von einer Studierenden der PH Wien, in der Lernwerkstatt \u201cAuditiv-kreatives Gestalten mit digitalen Medien\u201d (WS 23).<\/p>\n\n\n\n<h2 class=\"wp-block-heading alignwide has-text-align-center has-contrast-2-color has-base-background-color has-text-color has-background has-link-color has-medium-font-size wp-elements-642e91dc4d2898e74a6f95874d8f4dda\">Informationen:<\/h2>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-fixed-layout\"><tbody><tr><td>Produktion:<\/td><td>L. Brenneis (PH Wien, Wintersemester 23\/24)<\/td><\/tr><tr><td>Produktionsdatum:<\/td><td>21.01.2024<\/td><\/tr><tr><td>Creative Commons:<\/td><td><img decoding=\"async\" src=\"https:\/\/phmedien.rocks\/wp-content\/uploads\/2024\/10\/cc-by-nc-nd-e1729887615537.png\" alt=\"\"><\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Audio-Lernwerkstatt Herzlich willkommen zu einem fesselnden Gespr\u00e4ch rund um Deutsch als Fremdsprache (DaF) und Deutsch als Zweitsprache (DaZ) \u2013 speziell im Kontext von Deutschf\u00f6rderung in Schulen und der Erwachsenenbildung! Erfahrt mehr \u00fcber die Herausforderungen durch komplexe Rahmenbedingungen, mangelnde Ressourcen und die dringende Notwendigkeit eines Umdenkens im Unterricht, wobei es nicht nur um die Kluft zwischen [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":572,"comment_status":"open","ping_status":"closed","sticky":false,"template":"single-with-sidebar","format":"standard","meta":{"footnotes":""},"categories":[18,9],"tags":[],"class_list":["post-568","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-audio","category-medienarchiv"],"_links":{"self":[{"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/posts\/568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/comments?post=568"}],"version-history":[{"count":7,"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/posts\/568\/revisions"}],"predecessor-version":[{"id":1590,"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/posts\/568\/revisions\/1590"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/media\/572"}],"wp:attachment":[{"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/media?parent=568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/categories?post=568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/tags?post=568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}