{"id":405,"date":"2025-01-21T09:47:04","date_gmt":"2025-01-21T08:47:04","guid":{"rendered":"https:\/\/phmedien.rocks\/?p=405"},"modified":"2025-01-21T09:53:15","modified_gmt":"2025-01-21T08:53:15","slug":"interview-mit-teilnehmerinnen-und-teilnehmern-vom-hlg-persoenlichkeitsentwicklung-und-empowerment","status":"publish","type":"post","link":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/2025\/01\/21\/interview-mit-teilnehmerinnen-und-teilnehmern-vom-hlg-persoenlichkeitsentwicklung-und-empowerment\/","title":{"rendered":"Interview mit Teilnehmerinnen und Teilnehmern vom HLG &#8220; Pers\u00f6nlichkeitsentwicklung und Empowerment&#8220;"},"content":{"rendered":"\n<div class=\"wp-block-group alignwide is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading alignwide has-base-2-background-color has-background\" style=\"font-size:clamp(1.039rem, 1.039rem + ((1vw - 0.2rem) * 0.701), 1.6rem);\">BB Talks<\/h2>\n\n\n\n<p class=\"has-text-align-left has-base-background-color has-background has-heading-font-family has-small-font-size wp-block-paragraph\" style=\"border-style:none;border-width:0px;margin-top:0;margin-right:0;margin-bottom:0;margin-left:0;padding-top:0;padding-right:0;padding-bottom:0;padding-left:0;text-transform:none\">Podcast: Teilnehmerinnen und Teilnehmer vom HLG \u201ePers\u00f6nlichkeitsentwicklung und Empowerment\u201c <strong>Episode 7:\u00a0 Miteinander, Handlungsm\u00f6glichkeiten f\u00fcr inklusiven Unterricht in der beruflichen Bildung<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-left has-base-background-color has-background has-heading-font-family has-small-font-size wp-block-paragraph\" style=\"border-style:none;border-width:0px;margin-top:0;margin-right:0;margin-bottom:0;margin-left:0;padding-top:0;padding-right:0;padding-bottom:0;padding-left:0;text-transform:none\">Ich spreche mit Teilnehmerinnen und Teilnehmern von \u201ePers\u00f6nlichkeitsentwicklung und Empowerment\u201c \u00fcber die Erfahrungen mit diesem neuen Hochschullehrgang.<\/p>\n\n\n\n<p class=\"has-text-align-left has-base-background-color has-background has-heading-font-family has-small-font-size wp-block-paragraph\" style=\"border-style:none;border-width:0px;margin-top:0;margin-right:0;margin-bottom:0;margin-left:0;padding-top:0;padding-right:0;padding-bottom:0;padding-left:0;text-transform:none\">In der ersten Episode der Berufsbildungs Talks, sprach ich mit Ursula Sillaber \u00fcber die Inhalte des Hochschullehrgangs \u201ePers\u00f6nlichkeitsentwicklung und Empowerment\u201c. Der Lehrgang begann im heurigen Sommersemester und so dachten wir, dass es doch spannend w\u00e4re mit Teilnehmer*innen des Lehrgangs \u00fcber ihre Erfahrungen zu sprechen. Als erstes interviewte ich zwei P\u00e4dagoginnen mit einiger Berufserfahrung.<\/p>\n\n\n\n<p class=\"has-text-align-left has-base-background-color has-background has-heading-font-family has-small-font-size wp-block-paragraph\" style=\"border-style:none;border-width:0px;margin-top:0;margin-right:0;margin-bottom:0;margin-left:0;padding-top:0;padding-right:0;padding-bottom:0;padding-left:0;text-transform:none\">Pers\u00f6nlichkeitsentwicklung und Empowerment ist auch f\u00fcr die j\u00fcngeren Kollegen von Interesse. Der Bedarf an den Schulen ist gegeben, denn im Lehrberuf ist die Ausbildung nie zu Ende.<\/p>\n\n\n\n<p class=\"has-text-align-left has-base-background-color has-background has-heading-font-family has-small-font-size wp-block-paragraph\" style=\"border-style:none;border-width:0px;margin-top:0;margin-right:0;margin-bottom:0;margin-left:0;padding-top:0;padding-right:0;padding-bottom:0;padding-left:0;text-transform:none\">Dabei stehen Teamf\u00e4higkeit und Teamgeist ganz oben auf der Liste der Anforderungen f\u00fcr den allt\u00e4glichen Schulbetrieb.<\/p>\n\n\n\n<p class=\"has-text-align-left has-base-background-color has-background has-heading-font-family has-small-font-size wp-block-paragraph\" style=\"border-style:none;border-width:0px;margin-top:0;margin-right:0;margin-bottom:0;margin-left:0;padding-top:0;padding-right:0;padding-bottom:0;padding-left:0;text-transform:none\">Teamf\u00e4higkeit und Teamgeist st\u00e4rken, ich sprach mit Teilnehmerinnen und Teilnehmern des Hochschullehrgangs Pers\u00f6nlichkeitsentwicklung und Empowerment \u00fcber ihre Erfahrungen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading alignwide has-text-align-center has-contrast-2-color has-base-background-color has-text-color has-background has-link-color has-medium-font-size wp-elements-99227ddd712b4ee06ae362d2fb637693\">Podcast:<\/h2>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/phmedien.rocks\/wp-content\/uploads\/2024\/12\/Podcast_PH_007_HLG_Teiln.mp3\"><\/audio><\/figure>\n\n\n\n<h2 class=\"wp-block-heading alignwide has-text-align-center has-contrast-2-color has-base-background-color has-text-color has-background has-link-color has-medium-font-size wp-elements-6b6143582948c34b513924bd3444b54e\">Podcast mit Untertitel und \u00fcbersetzungen:<\/h2>\n\n\n<p><iframe loading=\"lazy\" src=\"https:\/\/phwien.cloud.panopto.eu\/Panopto\/Pages\/Embed.aspx?id=edcb1590-01fd-4751-aadd-b24200da948f&#038;autoplay=false&#038;offerviewer=true&#038;showtitle=true&#038;showbrand=true&#038;captions=false&#038;interactivity=all\" height=\"200\" width=\"100%\" style=\"border: 1px solid #464646;\" allowfullscreen allow=\"autoplay\" aria-label=\"In Panopto integrierter Videoplayer\" aria-description=\"Interview HLG Pers\u00f6nlichkeitsentwicklung\" ><\/iframe><\/p>\n\n\n\n<h2 class=\"wp-block-heading alignwide has-text-align-center has-contrast-2-color has-base-background-color has-text-color has-background has-link-color has-medium-font-size wp-elements-642e91dc4d2898e74a6f95874d8f4dda\">Informationen:<\/h2>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\" style=\"text-transform:none\"><table class=\"has-fixed-layout\"><tbody><tr><td>Produktion:<\/td><td>IBB PH Wien<\/td><\/tr><tr><td>Produktionsdatum:<\/td><td>02.11.2022<\/td><\/tr><tr><td>Creative Commons:<\/td><td><img decoding=\"async\" src=\"https:\/\/phmedien.rocks\/wp-content\/uploads\/2024\/10\/cc-by.png\" alt=\"\"><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>BB Talks Podcast: Teilnehmerinnen und Teilnehmer vom HLG \u201ePers\u00f6nlichkeitsentwicklung und Empowerment\u201c Episode 7:\u00a0 Miteinander, Handlungsm\u00f6glichkeiten f\u00fcr inklusiven Unterricht in der beruflichen Bildung Ich spreche mit Teilnehmerinnen und Teilnehmern von \u201ePers\u00f6nlichkeitsentwicklung und Empowerment\u201c \u00fcber die Erfahrungen mit diesem neuen Hochschullehrgang. In der ersten Episode der Berufsbildungs Talks, sprach ich mit Ursula Sillaber \u00fcber die Inhalte des [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":417,"comment_status":"open","ping_status":"open","sticky":false,"template":"single-with-sidebar","format":"standard","meta":{"footnotes":""},"categories":[18,9],"tags":[],"class_list":["post-405","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-audio","category-medienarchiv"],"_links":{"self":[{"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/posts\/405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/comments?post=405"}],"version-history":[{"count":7,"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/posts\/405\/revisions"}],"predecessor-version":[{"id":1641,"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/posts\/405\/revisions\/1641"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/media\/417"}],"wp:attachment":[{"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/media?parent=405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/categories?post=405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/tags?post=405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}