{"id":293,"date":"2025-01-20T11:32:03","date_gmt":"2025-01-20T10:32:03","guid":{"rendered":"https:\/\/phmedien.rocks\/?p=293"},"modified":"2025-01-20T20:11:24","modified_gmt":"2025-01-20T19:11:24","slug":"chaos-im-kopf-wie-junglehrer-die-ersten-dienstjahre-meistern","status":"publish","type":"post","link":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/2025\/01\/20\/chaos-im-kopf-wie-junglehrer-die-ersten-dienstjahre-meistern\/","title":{"rendered":"Chaos im Kopf \u2013 wie Junglehrer die ersten Dienstjahre meistern"},"content":{"rendered":"\n<div class=\"wp-block-group alignwide is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading alignwide has-base-2-background-color has-background\" style=\"font-size:clamp(1.039rem, 1.039rem + ((1vw - 0.2rem) * 0.701), 1.6rem);\">Audio-Lernwerkstatt<\/h2>\n\n\n\n<p class=\"has-text-align-left has-base-background-color has-background has-heading-font-family has-small-font-size wp-block-paragraph\" style=\"border-style:none;border-width:0px;margin-top:0;margin-right:0;margin-bottom:0;margin-left:0;padding-top:0;padding-right:0;padding-bottom:0;padding-left:0;text-transform:none\">Du f\u00e4ngst bald an, in einer Schule zu arbeiten, und m\u00f6chtest wissen, welche Herausforderungen auf dich zukommen? Hier erf\u00e4hrst du spannende Geschichten von zwei Lehrpersonen, die ihren Alltag mit dir teilen. Egal, ob du bereits seit Jahren in einer Schule arbeitest oder dich dieses Thema sehr interessiert, schnapp dir einen guten Tee, mach es dir bequem und genie\u00dfe!<\/p>\n\n\n\n<p class=\"has-text-align-left has-base-background-color has-background has-heading-font-family has-small-font-size wp-block-paragraph\" style=\"border-style:none;border-width:0px;margin-top:0;margin-right:0;margin-bottom:0;margin-left:0;padding-top:0;padding-right:0;padding-bottom:0;padding-left:0;text-transform:none\">Bist du bereit, dich auf eine kleine Entdeckungsreise hinter die T\u00fcren der Schule zu begeben und unsere Gedanken als Lehrkr\u00e4fte zu verfolgen, aber auch zahlreiche L\u00f6sungen f\u00fcr den schulischen Alltag zu entdecken? Vielen Dank, dass du ein Teil unsere Podcasts bist!<\/p>\n\n\n\n<h2 class=\"wp-block-heading alignwide has-text-align-center has-contrast-2-color has-base-background-color has-text-color has-background has-link-color has-medium-font-size wp-elements-99227ddd712b4ee06ae362d2fb637693\">Podcast:<\/h2>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/phmedien.rocks\/wp-content\/uploads\/2024\/11\/Chaos-im-Kopf_MACH_PONNER.mp3\"><\/audio><\/figure>\n\n\n<p><iframe loading=\"lazy\" src=\"https:\/\/phwien.cloud.panopto.eu\/Panopto\/Pages\/Embed.aspx?id=8eb85a11-680f-489f-bada-b234011bccd4&#038;autoplay=false&#038;offerviewer=true&#038;showtitle=true&#038;showbrand=true&#038;captions=false&#038;interactivity=all\" height=\"200\" width=\"100%\" style=\"border: 1px solid #464646;\" allowfullscreen allow=\"autoplay\" aria-label=\"In Panopto integrierter Videoplayer\" aria-description=\"Chaos im Kopf \u2013 wie Junglehrer die ersten Dienstjahre meistern\" ><\/iframe><\/p>\n\n\n\n<p class=\"has-base-background-color has-background has-small-font-size wp-block-paragraph\" style=\"padding-right:0;padding-left:0;text-transform:none\">Produziert von Studierenden der PH Wien, in der Lernwerkstatt \u201cAuditiv-kreatives Gestalten mit digitalen Medien\u201d (WS 23\/24).<\/p>\n\n\n\n<h2 class=\"wp-block-heading alignwide has-text-align-center has-contrast-2-color has-base-background-color has-text-color has-background has-link-color has-medium-font-size wp-elements-642e91dc4d2898e74a6f95874d8f4dda\">Informationen:<\/h2>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\" style=\"text-transform:none\"><table class=\"has-fixed-layout\"><tbody><tr><td>Produktion:<\/td><td>B. Ponner und J. Mach (PH Wien, Wintersemester 23\/24) Hintergrundmusik von Pixabay &#8211; Trap Future Bass (Royalty Free Music) ge\u00f6ffnet am 25.1.2024 https:\/\/pixabay.com\/de\/music\/zukunftiger-bass-trap-future-bass-royalty-free-music-167020\/<\/td><\/tr><tr><td>Produktionsdatum:<\/td><td>05.01.2024<\/td><\/tr><tr><td>Creative Commons:<\/td><td><img decoding=\"async\" src=\"https:\/\/phmedien.rocks\/wp-content\/uploads\/2024\/10\/cc-by-nc-nd-e1729887615537.png\" alt=\"\"><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Audio-Lernwerkstatt Du f\u00e4ngst bald an, in einer Schule zu arbeiten, und m\u00f6chtest wissen, welche Herausforderungen auf dich zukommen? Hier erf\u00e4hrst du spannende Geschichten von zwei Lehrpersonen, die ihren Alltag mit dir teilen. Egal, ob du bereits seit Jahren in einer Schule arbeitest oder dich dieses Thema sehr interessiert, schnapp dir einen guten Tee, mach es [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":419,"comment_status":"open","ping_status":"closed","sticky":false,"template":"single-with-sidebar","format":"standard","meta":{"footnotes":""},"categories":[18,9],"tags":[],"class_list":["post-293","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-audio","category-medienarchiv"],"_links":{"self":[{"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/posts\/293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/comments?post=293"}],"version-history":[{"count":7,"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/posts\/293\/revisions"}],"predecessor-version":[{"id":1589,"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/posts\/293\/revisions\/1589"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/media\/419"}],"wp:attachment":[{"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/media?parent=293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/categories?post=293"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/tags?post=293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}