{"id":1275,"date":"2025-01-20T21:44:06","date_gmt":"2025-01-20T20:44:06","guid":{"rendered":"https:\/\/phmedien.rocks\/?p=1275"},"modified":"2026-02-16T13:48:31","modified_gmt":"2026-02-16T12:48:31","slug":"christian-schreger-die-faszination-der-vielfalt","status":"publish","type":"post","link":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/2025\/01\/20\/christian-schreger-die-faszination-der-vielfalt\/","title":{"rendered":"Christian Schreger: Die Faszination der Vielfalt"},"content":{"rendered":"\n<div class=\"wp-block-group alignwide is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading alignwide has-base-2-background-color has-background\" style=\"font-size:clamp(1.039rem, 1.039rem + ((1vw - 0.2rem) * 0.701), 1.6rem);\">PH.ON.Wien &#8211; Erfahrungen aus dem Bildungsbereich #17<\/h2>\n\n\n\n<p class=\"has-text-align-left has-base-background-color has-background has-heading-font-family has-small-font-size wp-block-paragraph\" style=\"border-style:none;border-width:0px;margin-top:0;margin-right:0;margin-bottom:0;margin-left:0;padding-top:0;padding-right:0;padding-bottom:0;padding-left:0;text-transform:none\"><a href=\"http:\/\/ortnergasse.webonaut.com\/m2\/imprm2.html\" target=\"_blank\" rel=\"noreferrer noopener\">Christian Schreger<\/a>\u00a0ist langj\u00e4hriger Volkschullehrer und arbeitet in einer\u00a0<a href=\"http:\/\/ortnergasse.webonaut.com\/m2\/index.html\" target=\"_blank\" rel=\"noreferrer noopener\">Mehrstufenklasse (M2)<\/a>\u00a0an der\u00a0<a href=\"https:\/\/vs-ortnergasse.schule.wien.at\/\" target=\"_blank\" rel=\"noreferrer noopener\">VS Ortnergasse in 1150 Wien<\/a>. Im Gespr\u00e4ch mit\u00a0<a href=\"https:\/\/zli.phwien.ac.at\/team\/christian-berger\/\" target=\"_blank\" rel=\"noreferrer noopener\">Christian Berger<\/a>\u00a0erl\u00e4utert er, was ihn an der Arbeit fasziniert: es ist die Vielfalt. Die Vielfalt in den Kulturen und Sprachen, aber auch die Vielfalt der Wege des Lernens der Kinder. &#8222;Ununterbrochen gibt es was Neues zum Lernen&#8220;, b\u00fcndelt er seine Freude am Beruf aber auch daran immer wieder von den Kindern \u00fcberrascht und neugierig gehalten zu werden. Ausgangspunkt war die Freinetp\u00e4dagogik. Viele seiner Klassenprojekte sind auf der\u00a0<a href=\"http:\/\/ortnergasse.webonaut.com\/m2\/projekte\/index.html\" target=\"_blank\" rel=\"noreferrer noopener\">Projektseite M2<\/a>\u00a0nachzulesen. Manche seiner Methoden, wie das &#8222;<a href=\"http:\/\/ortnergasse.webonaut.com\/m2\/2019\/index.html\" target=\"_blank\" rel=\"noreferrer noopener\">digitale Tagebuch<\/a>&#8220; oder die &#8222;<a href=\"http:\/\/ortnergasse.webonaut.com\/m2\/kb\/index.html\" target=\"_blank\" rel=\"noreferrer noopener\">Kleinen B\u00fccher<\/a>&#8220; sind zum Vorbild f\u00fcr viele andere geworden. Durch die Zusammenarbeit mit der Sprachwissenschafterin Dr.\u00a0<a href=\"https:\/\/www.univie.ac.at\/germanistik\/brigitta-busch\/\" target=\"_blank\" rel=\"noreferrer noopener\">Brigitta Busch<\/a>\u00a0sind die &#8222;Kleinen B\u00fccher&#8220; auch schon bis in andere Kontinente vorgedrungen. Die dem Podcast beigef\u00fcgten Links laden dazu ein mehr \u00fcber die schulische Arbeit von Christian Schreger kennenzulernen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading alignwide has-text-align-center has-contrast-2-color has-base-background-color has-text-color has-background has-link-color has-medium-font-size wp-elements-99227ddd712b4ee06ae362d2fb637693\">Podcast:<\/h2>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/phmedien.rocks\/wp-content\/uploads\/2025\/01\/Die-Faszination-der-Vielfalt.mp3\"><\/audio><\/figure>\n\n\n\n<h2 class=\"wp-block-heading alignwide has-text-align-center has-contrast-2-color has-base-background-color has-text-color has-background has-link-color has-medium-font-size wp-elements-6b6143582948c34b513924bd3444b54e\">Podcast mit Untertitel und \u00fcbersetzungen:<\/h2>\n\n\n<p><iframe loading=\"lazy\" src=\"https:\/\/phwien.cloud.panopto.eu\/Panopto\/Pages\/Embed.aspx?id=e7528415-bc07-435a-942a-b261007a5963&#038;autoplay=false&#038;offerviewer=true&#038;showtitle=true&#038;showbrand=true&#038;captions=false&#038;interactivity=all\" height=\"200\" width=\"100%\" style=\"border: 1px solid #464646;\" allowfullscreen allow=\"autoplay\" aria-label=\"In Panopto integrierter Videoplayer\" aria-description=\"Die Faszination der Vielfalt\" ><\/iframe><\/p>\n\n\n\n<h2 class=\"wp-block-heading alignwide has-text-align-center has-contrast-2-color has-base-background-color has-text-color has-background has-link-color has-medium-font-size wp-elements-642e91dc4d2898e74a6f95874d8f4dda\">Informationen:<\/h2>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\" style=\"text-transform:none\"><table class=\"has-fixed-layout\"><tbody><tr><td>Produktion:<\/td><td>PH Wien \/ Medialab \/ Christian Berger<\/td><\/tr><tr><td>Produktionsdatum:<\/td><td>29.12.2019<\/td><\/tr><tr><td>Creative Commons:<\/td><td><img decoding=\"async\" src=\"https:\/\/phmedien.rocks\/wp-content\/uploads\/2024\/10\/cc-by.png\" alt=\"\"><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>PH.ON.Wien &#8211; Erfahrungen aus dem Bildungsbereich #17 Christian Schreger\u00a0ist langj\u00e4hriger Volkschullehrer und arbeitet in einer\u00a0Mehrstufenklasse (M2)\u00a0an der\u00a0VS Ortnergasse in 1150 Wien. Im Gespr\u00e4ch mit\u00a0Christian Berger\u00a0erl\u00e4utert er, was ihn an der Arbeit fasziniert: es ist die Vielfalt. Die Vielfalt in den Kulturen und Sprachen, aber auch die Vielfalt der Wege des Lernens der Kinder. &#8222;Ununterbrochen gibt [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":1320,"comment_status":"open","ping_status":"open","sticky":false,"template":"single-with-sidebar","format":"standard","meta":{"footnotes":""},"categories":[18,9,38],"tags":[],"class_list":["post-1275","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-audio","category-medienarchiv","category-phon"],"_links":{"self":[{"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/posts\/1275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/comments?post=1275"}],"version-history":[{"count":4,"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/posts\/1275\/revisions"}],"predecessor-version":[{"id":1631,"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/posts\/1275\/revisions\/1631"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/media\/1320"}],"wp:attachment":[{"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/media?parent=1275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/categories?post=1275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medienarchiv.phwien.ac.at\/index.php\/wp-json\/wp\/v2\/tags?post=1275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}